{"id":8,"date":"2016-05-26T12:21:55","date_gmt":"2016-05-26T10:21:55","guid":{"rendered":"http:\/\/www.free-miners.ch\/?page_id=8"},"modified":"2016-09-14T20:10:41","modified_gmt":"2016-09-14T18:10:41","slug":"goldwaschen-ausland","status":"publish","type":"page","link":"https:\/\/www.free-miners.ch\/index.php\/goldwaschen-ausland\/","title":{"rendered":"Goldwaschen Ausland"},"content":{"rendered":"<h2>GOLDWASCHEN IN SERBIEN MIT GOLD-DREDGE<\/h2>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/S9611XoZxyE\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-origwidth=\"560\" data-origheight=\"315\"><\/iframe><\/p>\n<p>Der Fr\u00fchling kommt \u2013 die Natur ruft!<\/p>\n<p>Wir freuen uns jetzt schon auf die Goldwasch-Saison dieses Jahres.<\/p>\n<p>Letztes Jahr waren wir mehrmals in Serbien Goldwaschen.<br \/>\nDiesen Sommer bieten wir gef\u00fchrte Kurse nach Serbien an.<\/p>\n<p>In einer traumhaften Natur abzuschalten und Gold zu waschen \u2013 von Hand oder maschinell \u2013 so oder so ein Highlight!<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/AAKpKN3GxOQ\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-origwidth=\"560\" data-origheight=\"315\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>Im Jahr 2015 reisten wir nach Serbien, prospektierten viele Fl\u00fcsse und B\u00e4che.<\/p>\n<p>Jetzt haben wir ein Gold-Camp mit Equipment, weniger als zwei Stunden von Belgrad entfernt.<\/p>\n<p>F\u00fcr jeden, der das Abenteuer reizt \u2013 ob Profi oder Amateur&#8230;<\/p>\n<p>&nbsp;<\/p>\n<p>mit unserer Instruktion wird jede Reise mit Gold enden\u2026<\/p>\n<p>&nbsp;<\/p>\n<p>Standartm\u00e4ssig bieten wir 7- oder 10-Tagesreisen an zu 1790 \/ 2390 CHF an. (Inkl. Miete 6\u2033 Keene Dregde)<\/p>\n<p>Sowie Goldwaschen von Hand in Serbien 7 Tage \/ 10 Tage \/ 14 Tag zu 790.- \/ 990.- \/ 1190.- CHF<\/p>\n<p>Inkl. im Reisepreis ist der Transport vom Flughafen Belgrad zum Goldcamp, \u00dcbernachtung, Voll-Pension, Essen &amp; Getr\u00e4nke all inkl.<\/p>\n<p>Die Reise nach Belgrad (Serbien) organisiert der Teilnehmer.<\/p>\n<p>Sowie Mitbenutzungsrecht unserer 6\u2033 Profi Keene Dredge \u00a0\u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0(inkl. Kompressor Lungenautomat zum Tauchen bis ca. 3 Meter)<\/p>\n<p>Das gefundene Gold wird unter den Goldw\u00e4schern aufgeteilt.<\/p>\n<p>Unsere Goldwasch Saison ist vom April bis Oktober. Andere Monate nur f\u00fcr Hardliner<\/p>\n<p>Ab ca. 5 Personen in der selben Woche, kann eine Reise geplant werden<\/p>\n<p>&nbsp;<\/p>\n<p>Unsere E-Mail Adresse:<\/p>\n<p>info@free-miners.ch<\/p>\n","protected":false},"excerpt":{"rendered":"<p>GOLDWASCHEN IN SERBIEN MIT GOLD-DREDGE Der Fr\u00fchling kommt \u2013 die Natur ruft! Wir freuen uns jetzt schon auf die Goldwasch-Saison dieses Jahres. Letztes Jahr waren wir mehrmals in Serbien Goldwaschen. Diesen Sommer bieten wir gef\u00fchrte Kurse nach Serbien an. In einer traumhaften Natur abzuschalten und Gold zu waschen \u2013 von Hand oder maschinell \u2013 so [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8","page","type-page","status-publish","hentry","post-preview"],"_links":{"self":[{"href":"https:\/\/www.free-miners.ch\/index.php\/wp-json\/wp\/v2\/pages\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.free-miners.ch\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.free-miners.ch\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.free-miners.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.free-miners.ch\/index.php\/wp-json\/wp\/v2\/comments?post=8"}],"version-history":[{"count":7,"href":"https:\/\/www.free-miners.ch\/index.php\/wp-json\/wp\/v2\/pages\/8\/revisions"}],"predecessor-version":[{"id":435,"href":"https:\/\/www.free-miners.ch\/index.php\/wp-json\/wp\/v2\/pages\/8\/revisions\/435"}],"wp:attachment":[{"href":"https:\/\/www.free-miners.ch\/index.php\/wp-json\/wp\/v2\/media?parent=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}